{"id":8831,"date":"2020-07-27T14:23:20","date_gmt":"2020-07-27T12:23:20","guid":{"rendered":"https:\/\/pann.nl\/staging\/?page_id=8831"},"modified":"2024-10-14T21:44:48","modified_gmt":"2024-10-14T19:44:48","slug":"word-vrijwilliger","status":"publish","type":"page","link":"https:\/\/pann.nl\/en\/word-vrijwilliger\/","title":{"rendered":"Become a volunteer"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8831\" class=\"elementor elementor-8831\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325c6466 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"325c6466\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-378b59f3\" data-id=\"378b59f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-506acbc3 elementor-widget elementor-widget-heading\" data-id=\"506acbc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Volunteer vacancies<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-478073e9 elementor-grid-eael-col-3 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"478073e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-3&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-478073e9\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-478073e9 eael-post-grid-style-three\" data-layout-mode=\"grid\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-14969 tags-open\" data-id=\"14969\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/teamleider-25\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-14972\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56-768x512.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56-297x198.jpg 297w, https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56-842x561.jpg 842w, https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56-1536x1024.jpg 1536w, https:\/\/pann.nl\/wp-content\/uploads\/2024\/02\/PANN25-56.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/teamleider-25\/\" title=\"Team leader 25+\">Team leader 25+<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Do you have a true team leader mentality? Are you a pro at last-minute struggles? And do you want to work together...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/teamleider-25\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-12764 tags-open\" data-id=\"12764\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/videograaf\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12695\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595-768x512.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595-297x198.jpg 297w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595-842x561.jpg 842w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595-1536x1024.jpg 1536w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/MG_5595.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/videograaf\/\" title=\"Videographer\">Videographer<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Do you have a love of video and a passion for the night? And preferably those...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/videograaf\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10525 tags-open\" data-id=\"10525\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/teamlid-vrijwilligerszaken\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-18388\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-768x512.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-297x198.jpg 297w, https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-842x561.jpg 842w, https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-1536x1024.jpg 1536w, https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken-18x12.jpg 18w, https:\/\/pann.nl\/wp-content\/uploads\/2022\/11\/Vrijwilligerszaken.jpg 1800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/teamlid-vrijwilligerszaken\/\" title=\"Team member Volunteer Affairs\">Team member Volunteer Affairs<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Do you enjoy helping people? Contributing to the next step...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/teamlid-vrijwilligerszaken\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-12781 tags-open\" data-id=\"12781\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/mc-specialist\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-14938\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-768x512.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-297x198.jpg 297w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-842x561.jpg 842w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-1536x1024.jpg 1536w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/DSC01529-2048x1365.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/mc-specialist\/\" title=\"Content creator\">Content creator<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Are you addicted to social media? Don't get bored of TikTok and Instagram and lie...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/mc-specialist\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10007 tags-open\" data-id=\"10007\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/vj\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"191\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2017\/09\/vacature-vj-768x191.jpg\" class=\"attachment-medium_large size-medium_large wp-image-7115\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2017\/09\/vacature-vj-768x191.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2017\/09\/vacature-vj-300x75.jpg 300w, https:\/\/pann.nl\/wp-content\/uploads\/2017\/09\/vacature-vj.jpg 795w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/vj\/\" title=\"VJ\">VJ<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Do you like mixing the hottest images on our stage? Do you put during...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/vj\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-12771 tags-open\" data-id=\"12771\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay none\"><i class=\"\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/pann.nl\/en\/vacatures\/vj-coordinator\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                 <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12621\" alt=\"\" srcset=\"https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-768x512.jpg 768w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-297x198.jpg 297w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-841x561.jpg 841w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-1536x1024.jpg 1536w, https:\/\/pann.nl\/wp-content\/uploads\/2023\/03\/IMG_3249-2048x1365.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n             <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h4 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/pann.nl\/en\/vacatures\/vj-coordinator\/\" title=\"VJ coordinator\">VJ coordinator<\/a><\/h4><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>As VJ coordinator, you and your team will ensure the best visual effects during a...<\/p><a href=\"https:\/\/pann.nl\/en\/vacatures\/vj-coordinator\/\" class=\"eael-post-elements-readmore-btn\">More info<\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Vrijwilligers vacatures Bestuur | Secretaris Voor Stichting PANN zoeken wij een secretaris die het bestuur komt versterken. Heb jij goede mondelinge&#8230; Meer info Bestuur | Penningmeester Word jij vrijwilliger bij PANN? Jij bent de financi\u00eble wizard van Stichting PANN en PANN50 (de&#8230; Meer info Teamleider 25+ Heb jij een echte teamleidersmentaliteit? Ben jij een pro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8831","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:34:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"pp_notify_user","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/pages\/8831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/comments?post=8831"}],"version-history":[{"count":64,"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/pages\/8831\/revisions"}],"predecessor-version":[{"id":16296,"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/pages\/8831\/revisions\/16296"}],"wp:attachment":[{"href":"https:\/\/pann.nl\/en\/wp-json\/wp\/v2\/media?parent=8831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}